{"id":23916,"date":"2026-07-04T18:55:05","date_gmt":"2026-07-04T16:55:05","guid":{"rendered":"https:\/\/artapartamento.com\/?page_id=23916"},"modified":"2026-07-04T18:57:55","modified_gmt":"2026-07-04T16:57:55","slug":"el-palacio-20","status":"publish","type":"page","link":"https:\/\/artapartamento.com\/it\/el-palacio-20\/","title":{"rendered":"El Palacio 20"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"23916\" class=\"elementor elementor-23916\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35d0804a e-con-full e-flex e-con e-parent\" data-id=\"35d0804a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-61bb0a30 e-con-full e-flex e-con e-child\" data-id=\"61bb0a30\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e55cb1b elementor-widget elementor-widget-image-carousel\" data-id=\"5e55cb1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello di immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 1\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"5e55cb1b\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTM3MzksInVybCI6Imh0dHBzOlwvXC9hcnRhcGFydGFtZW50by5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjVcLzAxXC9FTC1QQUxBQ0lPLTIwLTEzMHgxMDAtc3RyYXBwby1lbi1hY3JpbGljby1zLWxpZW56by0yMDI0LXNjYWxlZC5qcGcud2VicCIsInNsaWRlc2hvdyI6IjVlNTVjYjFiIn0%3D\" href=\"https:\/\/artapartamento.com\/wp-content\/uploads\/2025\/01\/EL-PALACIO-20-130x100-strappo-en-acrilico-s-lienzo-2024-scaled.jpg.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/artapartamento.com\/wp-content\/uploads\/2025\/01\/EL-PALACIO-20-130x100-strappo-en-acrilico-s-lienzo-2024-scaled.jpg.webp\" alt=\"Eloy Arribas\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5d51fcdc e-con-full e-flex e-con e-child\" data-id=\"5d51fcdc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-727333c7 elementor-widget elementor-widget-heading\" data-id=\"727333c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/artapartamento.com\/it\/category\/artistas\/eloy-arribas\/\" rel=\"tag\">Eloy Arribas<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41052003 elementor-widget elementor-widget-text-editor\" data-id=\"41052003\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Palacio 20, 2024<\/p><p>Strappo in acrilico e olio su tela<\/p><p>130 x 100 cm<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19cc4540 elementor-widget elementor-widget-text-editor\" data-id=\"19cc4540\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Impronta e incidente si confondono con grafia e gesto. La memoria si confonde con il racconto, e la pittura si confonde con l'archivio. L'artista porta all'estremo, in modo piuttosto innovativo, la logica moderna dell'originale multiplo. E, in modo molto sottile ma maturo, scompone la nostra comprensione materiale della superficie pittorica, arricchendo il suo linguaggio con tecniche artistiche pi\u00f9 legate a discipline come il restauro e la conservazione delle opere d'arte, la museografia o l'architettura. Quella visione, tipica degli artisti rinascimentali italiani, secondo cui un dipinto \u00e8 una finestra aperta (flusso di illusione architettonica), qui \u00e8 sostituita da un muro, uno specchio d'acqua riflettente, un corpo vacillante; un archivio.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53713f72 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"53713f72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"mailto:info@artapartamento.com?subject=Inquiry%20Eloy%20Arribas&#038;body=El%20Palacio%2020%2C%202024%0AStrappo%20en%20acr%C3%ADlico%20y%20%C3%B3leo%20sobre%20lienzo%0A130%20x%20100%20cm\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiesta di informazioni<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>El Palacio 20, 2024 Strappo en acr\u00edlico y \u00f3leo sobre lienzo 130 x 100 cm Huella y accidente se confunden con graf\u00eda y gesto. Memoria se confunde con relato, y pintura se confunde con archivo. El artista lleva al extremo, de una forma bastante novedosa, la l\u00f3gica moderna del original m\u00faltiple. Y desdobla, de una [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13739,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[90],"tags":[65],"class_list":["post-23916","page","type-page","status-publish","has-post-thumbnail","hentry","category-eloy-arribas","tag-obra","post","post-with-thumbnail","post-with-thumbnail-large"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Eloy Arribas El Palacio 20, 2024Strappo en acr\u00edlico y \u00f3leo sobre lienzo130 x 100 cm Huella y accidente se confunden con graf\u00eda y gesto. Memoria se confunde con relato, y pintura se confunde con archivo. El artista lleva al extremo, de una forma bastante novedosa, la l\u00f3gica moderna del original m\u00faltiple. Y desdobla, de una\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/artapartamento.com\/it\/el-palacio-20\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Apartamento |\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Palacio 20 | El Apartamento\" \/>\n\t\t<meta property=\"og:description\" content=\"Eloy Arribas El Palacio 20, 2024Strappo en acr\u00edlico y \u00f3leo sobre lienzo130 x 100 cm Huella y accidente se confunden con graf\u00eda y gesto. Memoria se confunde con relato, y pintura se confunde con archivo. El artista lleva al extremo, de una forma bastante novedosa, la l\u00f3gica moderna del original m\u00faltiple. Y desdobla, de una\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/artapartamento.com\/it\/el-palacio-20\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/artapartamento.com\/wp-content\/uploads\/2025\/01\/EL-PALACIO-20-130x100-strappo-en-acrilico-s-lienzo-2024-scaled.jpg.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/artapartamento.com\/wp-content\/uploads\/2025\/01\/EL-PALACIO-20-130x100-strappo-en-acrilico-s-lienzo-2024-scaled.jpg.webp\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1976\" \/>\n\t\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-04T16:55:05+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-04T16:57:55+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/El-Apartamento-100069634825594\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Palacio 20 | El Apartamento\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Eloy Arribas El Palacio 20, 2024Strappo en acr\u00edlico y \u00f3leo sobre lienzo130 x 100 cm Huella y accidente se confunden con graf\u00eda y gesto. Memoria se confunde con relato, y pintura se confunde con archivo. El artista lleva al extremo, de una forma bastante novedosa, la l\u00f3gica moderna del original m\u00faltiple. Y desdobla, de una\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/artapartamento.com\/wp-content\/uploads\/2023\/08\/El-Apartamento.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/artapartamento.com\\\/it\\\/el-palacio-20\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/artapartamento.com\\\/it#listItem\",\"position\":1,\"name\":\"Hogar\",\"item\":\"https:\\\/\\\/artapartamento.com\\\/it\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/artapartamento.com\\\/it\\\/el-palacio-20\\\/#listItem\",\"name\":\"El Palacio 20\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/artapartamento.com\\\/it\\\/el-palacio-20\\\/#listItem\",\"position\":2,\"name\":\"El Palacio 20\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/artapartamento.com\\\/it#listItem\",\"name\":\"Hogar\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/artapartamento.com\\\/it\\\/#organization\",\"name\":\"El Apartamento\",\"url\":\"https:\\\/\\\/artapartamento.com\\\/it\\\/\",\"telephone\":\"+5352657535\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/artapartamento.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/El-Apartamento-_-Identidad-_-Perfil-RS-03.png.webp\",\"@id\":\"https:\\\/\\\/artapartamento.com\\\/it\\\/el-palacio-20\\\/#organizationLogo\",\"width\":474,\"height\":474,\"caption\":\"El Apartamento\"},\"image\":{\"@id\":\"https:\\\/\\\/artapartamento.com\\\/it\\\/el-palacio-20\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/El-Apartamento-100069634825594\\\/\",\"https:\\\/\\\/www.instagram.com\\\/art_apartamento\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/artapartamento.com\\\/it\\\/el-palacio-20\\\/#webpage\",\"url\":\"https:\\\/\\\/artapartamento.com\\\/it\\\/el-palacio-20\\\/\",\"name\":\"El Palacio 20 | El Apartamento\",\"description\":\"Eloy Arribas El Palacio 20, 2024Strappo en acr\\u00edlico y \\u00f3leo sobre lienzo130 x 100 cm Huella y accidente se confunden con graf\\u00eda y gesto. Memoria se confunde con relato, y pintura se confunde con archivo. El artista lleva al extremo, de una forma bastante novedosa, la l\\u00f3gica moderna del original m\\u00faltiple. Y desdobla, de una\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/artapartamento.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/artapartamento.com\\\/it\\\/el-palacio-20\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/artapartamento.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/EL-PALACIO-20-130x100-strappo-en-acrilico-s-lienzo-2024-scaled.jpg.webp\",\"@id\":\"https:\\\/\\\/artapartamento.com\\\/it\\\/el-palacio-20\\\/#mainImage\",\"width\":1976,\"height\":2560,\"caption\":\"Eloy Arribas\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/artapartamento.com\\\/it\\\/el-palacio-20\\\/#mainImage\"},\"datePublished\":\"2026-07-04T18:55:05+02:00\",\"dateModified\":\"2026-07-04T18:57:55+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/artapartamento.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/artapartamento.com\\\/it\\\/\",\"name\":\"El Apartamento\",\"alternateName\":\"El Apartamento\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/artapartamento.com\\\/it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El Palacio 20 | El Apartamento","description":"Eloy Arribas El Palacio 20, 2024Strappo en acr\u00edlico y \u00f3leo sobre lienzo130 x 100 cm Huella y accidente se confunden con graf\u00eda y gesto. Memoria se confunde con relato, y pintura se confunde con archivo. El artista lleva al extremo, de una forma bastante novedosa, la l\u00f3gica moderna del original m\u00faltiple. Y desdobla, de una","canonical_url":"https:\/\/artapartamento.com\/it\/el-palacio-20\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/artapartamento.com\/it\/el-palacio-20\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/artapartamento.com\/it#listItem","position":1,"name":"Hogar","item":"https:\/\/artapartamento.com\/it","nextItem":{"@type":"ListItem","@id":"https:\/\/artapartamento.com\/it\/el-palacio-20\/#listItem","name":"El Palacio 20"}},{"@type":"ListItem","@id":"https:\/\/artapartamento.com\/it\/el-palacio-20\/#listItem","position":2,"name":"El Palacio 20","previousItem":{"@type":"ListItem","@id":"https:\/\/artapartamento.com\/it#listItem","name":"Hogar"}}]},{"@type":"Organization","@id":"https:\/\/artapartamento.com\/it\/#organization","name":"El Apartamento","url":"https:\/\/artapartamento.com\/it\/","telephone":"+5352657535","logo":{"@type":"ImageObject","url":"https:\/\/artapartamento.com\/wp-content\/uploads\/2023\/11\/El-Apartamento-_-Identidad-_-Perfil-RS-03.png.webp","@id":"https:\/\/artapartamento.com\/it\/el-palacio-20\/#organizationLogo","width":474,"height":474,"caption":"El Apartamento"},"image":{"@id":"https:\/\/artapartamento.com\/it\/el-palacio-20\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/p\/El-Apartamento-100069634825594\/","https:\/\/www.instagram.com\/art_apartamento\/"]},{"@type":"WebPage","@id":"https:\/\/artapartamento.com\/it\/el-palacio-20\/#webpage","url":"https:\/\/artapartamento.com\/it\/el-palacio-20\/","name":"El Palacio 20 | El Apartamento","description":"Eloy Arribas El Palacio 20, 2024Strappo en acr\u00edlico y \u00f3leo sobre lienzo130 x 100 cm Huella y accidente se confunden con graf\u00eda y gesto. Memoria se confunde con relato, y pintura se confunde con archivo. El artista lleva al extremo, de una forma bastante novedosa, la l\u00f3gica moderna del original m\u00faltiple. Y desdobla, de una","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/artapartamento.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/artapartamento.com\/it\/el-palacio-20\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/artapartamento.com\/wp-content\/uploads\/2025\/01\/EL-PALACIO-20-130x100-strappo-en-acrilico-s-lienzo-2024-scaled.jpg.webp","@id":"https:\/\/artapartamento.com\/it\/el-palacio-20\/#mainImage","width":1976,"height":2560,"caption":"Eloy Arribas"},"primaryImageOfPage":{"@id":"https:\/\/artapartamento.com\/it\/el-palacio-20\/#mainImage"},"datePublished":"2026-07-04T18:55:05+02:00","dateModified":"2026-07-04T18:57:55+02:00"},{"@type":"WebSite","@id":"https:\/\/artapartamento.com\/it\/#website","url":"https:\/\/artapartamento.com\/it\/","name":"El Apartamento","alternateName":"El Apartamento","inLanguage":"it-IT","publisher":{"@id":"https:\/\/artapartamento.com\/it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"El Apartamento |","og:type":"article","og:title":"El Palacio 20 | El Apartamento","og:description":"Eloy Arribas El Palacio 20, 2024Strappo en acr\u00edlico y \u00f3leo sobre lienzo130 x 100 cm Huella y accidente se confunden con graf\u00eda y gesto. Memoria se confunde con relato, y pintura se confunde con archivo. El artista lleva al extremo, de una forma bastante novedosa, la l\u00f3gica moderna del original m\u00faltiple. Y desdobla, de una","og:url":"https:\/\/artapartamento.com\/it\/el-palacio-20\/","og:image":"https:\/\/artapartamento.com\/wp-content\/uploads\/2025\/01\/EL-PALACIO-20-130x100-strappo-en-acrilico-s-lienzo-2024-scaled.jpg.webp","og:image:secure_url":"https:\/\/artapartamento.com\/wp-content\/uploads\/2025\/01\/EL-PALACIO-20-130x100-strappo-en-acrilico-s-lienzo-2024-scaled.jpg.webp","og:image:width":1976,"og:image:height":2560,"article:published_time":"2026-07-04T16:55:05+00:00","article:modified_time":"2026-07-04T16:57:55+00:00","article:publisher":"https:\/\/www.facebook.com\/p\/El-Apartamento-100069634825594\/","twitter:card":"summary_large_image","twitter:title":"El Palacio 20 | El Apartamento","twitter:description":"Eloy Arribas El Palacio 20, 2024Strappo en acr\u00edlico y \u00f3leo sobre lienzo130 x 100 cm Huella y accidente se confunden con graf\u00eda y gesto. Memoria se confunde con relato, y pintura se confunde con archivo. El artista lleva al extremo, de una forma bastante novedosa, la l\u00f3gica moderna del original m\u00faltiple. Y desdobla, de una","twitter:image":"https:\/\/artapartamento.com\/wp-content\/uploads\/2023\/08\/El-Apartamento.png"},"aioseo_meta_data":{"post_id":"23916","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-07-04 16:55:07","updated":"2026-07-04 16:55:07","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/artapartamento.com\/it\" title=\"Hogar\">Hogar<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl Palacio 20\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Hogar","link":"https:\/\/artapartamento.com\/it"},{"label":"El Palacio 20","link":"https:\/\/artapartamento.com\/it\/el-palacio-20\/"}],"_links":{"self":[{"href":"https:\/\/artapartamento.com\/it\/wp-json\/wp\/v2\/pages\/23916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artapartamento.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/artapartamento.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/artapartamento.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/artapartamento.com\/it\/wp-json\/wp\/v2\/comments?post=23916"}],"version-history":[{"count":4,"href":"https:\/\/artapartamento.com\/it\/wp-json\/wp\/v2\/pages\/23916\/revisions"}],"predecessor-version":[{"id":23923,"href":"https:\/\/artapartamento.com\/it\/wp-json\/wp\/v2\/pages\/23916\/revisions\/23923"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artapartamento.com\/it\/wp-json\/wp\/v2\/media\/13739"}],"wp:attachment":[{"href":"https:\/\/artapartamento.com\/it\/wp-json\/wp\/v2\/media?parent=23916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/artapartamento.com\/it\/wp-json\/wp\/v2\/categories?post=23916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/artapartamento.com\/it\/wp-json\/wp\/v2\/tags?post=23916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}