{"id":23261,"date":"2026-06-20T21:56:07","date_gmt":"2026-06-20T19:56:07","guid":{"rendered":"https:\/\/artapartamento.com\/?page_id=23261"},"modified":"2026-06-20T21:57:59","modified_gmt":"2026-06-20T19:57:59","slug":"from-the-suspiros-de-arena-series-12","status":"publish","type":"page","link":"https:\/\/artapartamento.com\/fr\/from-the-suspiros-de-arena-series-12\/","title":{"rendered":"From the Suspiros de Arena series"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"23261\" class=\"elementor elementor-23261\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-250303a8 e-con-full e-flex e-con e-parent\" data-id=\"250303a8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-206ad103 e-con-full e-flex e-con e-child\" data-id=\"206ad103\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1cf1cc02 elementor-widget elementor-widget-image-carousel\" data-id=\"1cf1cc02\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d&#039;images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 1\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1cf1cc02\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyNTcsInVybCI6Imh0dHBzOlwvXC9hcnRhcGFydGFtZW50by5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjZcLzA2XC8xNC5Gcm9tLXRoZS1TdXNwaXJvcy1kZS1BcmVuYS1zZXJpZXMtMjAyNS5wbmcud2VicCIsInNsaWRlc2hvdyI6IjFjZjFjYzAyIn0%3D\" href=\"https:\/\/artapartamento.com\/wp-content\/uploads\/2026\/06\/14.From-the-Suspiros-de-Arena-series-2025.png.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/artapartamento.com\/wp-content\/uploads\/2026\/06\/14.From-the-Suspiros-de-Arena-series-2025.png.webp\" alt=\"14.From the Suspiros de Arena series, 2025. Arles\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-79c0473a e-con-full e-flex e-con e-child\" data-id=\"79c0473a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b810872 elementor-widget elementor-widget-heading\" data-id=\"b810872\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/artapartamento.com\/fr\/category\/artistas\/arles-del-rio\/\" rel=\"tag\">Arles del Rio<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d7747aa elementor-widget elementor-widget-text-editor\" data-id=\"6d7747aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>From the Suspiros de Arena series, 2025<\/p><p>Sea sand on raw canvas<\/p><p>100 x 100 cm (39.4 x 39.4 in)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a842d7 elementor-widget elementor-widget-text-editor\" data-id=\"8a842d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201c Suspiros de arena \u201d (Soupirs de sable) est n\u00e9 d'un geste \u00e0 mi-chemin entre le primitif et le m\u00e9ditatif : prendre du sable dans ses mains et le laisser tomber intentionnellement sur la toile brute, comme si chaque forme \u00e9tait un souffle suspendu, un soupir qui ancre l'instant. Cette technique \u00e9voque le rythme organique de la respiration : inspirer, expirer ; prendre, l\u00e2cher ; exister.<\/p><p>Les formes douces qui se r\u00e9v\u00e8lent ne cherchent pas \u00e0 repr\u00e9senter autre chose qu'elles-m\u00eames. Ce ne sont pas des images, mais des pr\u00e9sences. Des couches de sable marin qui font allusion au voyage invisible et persistant du sable \u00e0 travers le vent, \u00e0 son transit constant entre les lieux, les temps et les corps. Ces \u0153uvres rendent hommage \u00e0 l'impermanence, mais expriment \u00e9galement une volont\u00e9 de permanence : celle de fixer l'\u00e9ph\u00e9m\u00e8re dans la m\u00e9moire de la toile.<\/p><p>Suspiros de arena est une pratique de pleine conscience o\u00f9 le corps, la mati\u00e8re et le temps se confondent. Il ne s'agit pas de cr\u00e9er des formes, mais de les laisser \u00e9merger. Dans leur apparente douceur, ces pi\u00e8ces renferment la m\u00e9moire du mouvement, la fragilit\u00e9 de l'instant et une invitation silencieuse \u00e0 la pr\u00e9sence.\u00a0 \u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20361962 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"20361962\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"mailto:info@artapartamento.com?subject=Inquiry%20Arl%C3%A9s%20del%20Rio&#038;body=From%20the%20Suspiros%20de%20Arena%20series%2C%202025%0ASea%20sand%20on%20raw%20canvas%0A100%20x%20100%20cm%20(39.4%20x%2039.4%20in)\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Demande de renseignements<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>From the Suspiros de Arena series, 2025 Sea sand on raw canvas 100 x 100 cm (39.4 x 39.4 in) \u201cSuspiros de arena\u201d nace de un gesto que se define entre primario y meditativo: tomar arena entre las manos y soltarla con intenci\u00f3n sobre el lienzo crudo, como si cada forma fuera un aliento suspendido, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23257,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[43],"tags":[65],"class_list":["post-23261","page","type-page","status-publish","has-post-thumbnail","hentry","category-arles-del-rio","tag-obra","post","post-with-thumbnail","post-with-thumbnail-large"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Arl\u00e9s del R\u00edo From the Suspiros de Arena series, 2025Sea sand on raw canvas100 x 100 cm (39.4 x 39.4 in) \u201cSuspiros de arena\u201d nace de un gesto que se define entre primario y meditativo: tomar arena entre las manos y soltarla con intenci\u00f3n sobre el lienzo crudo, como si cada forma fuera un aliento\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/artapartamento.com\/fr\/from-the-suspiros-de-arena-series-12\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"El Apartamento |\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"From the Suspiros de Arena series | El Apartamento\" \/>\n\t\t<meta property=\"og:description\" content=\"Arl\u00e9s del R\u00edo From the Suspiros de Arena series, 2025Sea sand on raw canvas100 x 100 cm (39.4 x 39.4 in) \u201cSuspiros de arena\u201d nace de un gesto que se define entre primario y meditativo: tomar arena entre las manos y soltarla con intenci\u00f3n sobre el lienzo crudo, como si cada forma fuera un aliento\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/artapartamento.com\/fr\/from-the-suspiros-de-arena-series-12\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/artapartamento.com\/wp-content\/uploads\/2026\/06\/14.From-the-Suspiros-de-Arena-series-2025.png.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/artapartamento.com\/wp-content\/uploads\/2026\/06\/14.From-the-Suspiros-de-Arena-series-2025.png.webp\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1348\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1340\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-06-20T19:56:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-20T19:57:59+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/El-Apartamento-100069634825594\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"From the Suspiros de Arena series | El Apartamento\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Arl\u00e9s del R\u00edo From the Suspiros de Arena series, 2025Sea sand on raw canvas100 x 100 cm (39.4 x 39.4 in) \u201cSuspiros de arena\u201d nace de un gesto que se define entre primario y meditativo: tomar arena entre las manos y soltarla con intenci\u00f3n sobre el lienzo crudo, como si cada forma fuera un aliento\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/artapartamento.com\/wp-content\/uploads\/2023\/08\/El-Apartamento.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/artapartamento.com\\\/fr\\\/from-the-suspiros-de-arena-series-12\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/artapartamento.com\\\/fr#listItem\",\"position\":1,\"name\":\"Hogar\",\"item\":\"https:\\\/\\\/artapartamento.com\\\/fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/artapartamento.com\\\/fr\\\/from-the-suspiros-de-arena-series-12\\\/#listItem\",\"name\":\"From the Suspiros de Arena series\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/artapartamento.com\\\/fr\\\/from-the-suspiros-de-arena-series-12\\\/#listItem\",\"position\":2,\"name\":\"From the Suspiros de Arena series\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/artapartamento.com\\\/fr#listItem\",\"name\":\"Hogar\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/artapartamento.com\\\/fr\\\/#organization\",\"name\":\"El Apartamento\",\"url\":\"https:\\\/\\\/artapartamento.com\\\/fr\\\/\",\"telephone\":\"+5352657535\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/artapartamento.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/El-Apartamento-_-Identidad-_-Perfil-RS-03.png.webp\",\"@id\":\"https:\\\/\\\/artapartamento.com\\\/fr\\\/from-the-suspiros-de-arena-series-12\\\/#organizationLogo\",\"width\":474,\"height\":474,\"caption\":\"El Apartamento\"},\"image\":{\"@id\":\"https:\\\/\\\/artapartamento.com\\\/fr\\\/from-the-suspiros-de-arena-series-12\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/p\\\/El-Apartamento-100069634825594\\\/\",\"https:\\\/\\\/www.instagram.com\\\/art_apartamento\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/artapartamento.com\\\/fr\\\/from-the-suspiros-de-arena-series-12\\\/#webpage\",\"url\":\"https:\\\/\\\/artapartamento.com\\\/fr\\\/from-the-suspiros-de-arena-series-12\\\/\",\"name\":\"From the Suspiros de Arena series | El Apartamento\",\"description\":\"Arl\\u00e9s del R\\u00edo From the Suspiros de Arena series, 2025Sea sand on raw canvas100 x 100 cm (39.4 x 39.4 in) \\u201cSuspiros de arena\\u201d nace de un gesto que se define entre primario y meditativo: tomar arena entre las manos y soltarla con intenci\\u00f3n sobre el lienzo crudo, como si cada forma fuera un aliento\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/artapartamento.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/artapartamento.com\\\/fr\\\/from-the-suspiros-de-arena-series-12\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/artapartamento.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/14.From-the-Suspiros-de-Arena-series-2025.png.webp\",\"@id\":\"https:\\\/\\\/artapartamento.com\\\/fr\\\/from-the-suspiros-de-arena-series-12\\\/#mainImage\",\"width\":1348,\"height\":1340,\"caption\":\"14.From the Suspiros de Arena series, 2025\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/artapartamento.com\\\/fr\\\/from-the-suspiros-de-arena-series-12\\\/#mainImage\"},\"datePublished\":\"2026-06-20T21:56:07+02:00\",\"dateModified\":\"2026-06-20T21:57:59+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/artapartamento.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/artapartamento.com\\\/fr\\\/\",\"name\":\"El Apartamento\",\"alternateName\":\"El Apartamento\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/artapartamento.com\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"From the Suspiros de Arena series | El Apartamento","description":"Arl\u00e9s del R\u00edo From the Suspiros de Arena series, 2025Sea sand on raw canvas100 x 100 cm (39.4 x 39.4 in) \u201cSuspiros de arena\u201d nace de un gesto que se define entre primario y meditativo: tomar arena entre las manos y soltarla con intenci\u00f3n sobre el lienzo crudo, como si cada forma fuera un aliento","canonical_url":"https:\/\/artapartamento.com\/fr\/from-the-suspiros-de-arena-series-12\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/artapartamento.com\/fr\/from-the-suspiros-de-arena-series-12\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/artapartamento.com\/fr#listItem","position":1,"name":"Hogar","item":"https:\/\/artapartamento.com\/fr","nextItem":{"@type":"ListItem","@id":"https:\/\/artapartamento.com\/fr\/from-the-suspiros-de-arena-series-12\/#listItem","name":"From the Suspiros de Arena series"}},{"@type":"ListItem","@id":"https:\/\/artapartamento.com\/fr\/from-the-suspiros-de-arena-series-12\/#listItem","position":2,"name":"From the Suspiros de Arena series","previousItem":{"@type":"ListItem","@id":"https:\/\/artapartamento.com\/fr#listItem","name":"Hogar"}}]},{"@type":"Organization","@id":"https:\/\/artapartamento.com\/fr\/#organization","name":"El Apartamento","url":"https:\/\/artapartamento.com\/fr\/","telephone":"+5352657535","logo":{"@type":"ImageObject","url":"https:\/\/artapartamento.com\/wp-content\/uploads\/2023\/11\/El-Apartamento-_-Identidad-_-Perfil-RS-03.png.webp","@id":"https:\/\/artapartamento.com\/fr\/from-the-suspiros-de-arena-series-12\/#organizationLogo","width":474,"height":474,"caption":"El Apartamento"},"image":{"@id":"https:\/\/artapartamento.com\/fr\/from-the-suspiros-de-arena-series-12\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/p\/El-Apartamento-100069634825594\/","https:\/\/www.instagram.com\/art_apartamento\/"]},{"@type":"WebPage","@id":"https:\/\/artapartamento.com\/fr\/from-the-suspiros-de-arena-series-12\/#webpage","url":"https:\/\/artapartamento.com\/fr\/from-the-suspiros-de-arena-series-12\/","name":"From the Suspiros de Arena series | El Apartamento","description":"Arl\u00e9s del R\u00edo From the Suspiros de Arena series, 2025Sea sand on raw canvas100 x 100 cm (39.4 x 39.4 in) \u201cSuspiros de arena\u201d nace de un gesto que se define entre primario y meditativo: tomar arena entre las manos y soltarla con intenci\u00f3n sobre el lienzo crudo, como si cada forma fuera un aliento","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/artapartamento.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/artapartamento.com\/fr\/from-the-suspiros-de-arena-series-12\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/artapartamento.com\/wp-content\/uploads\/2026\/06\/14.From-the-Suspiros-de-Arena-series-2025.png.webp","@id":"https:\/\/artapartamento.com\/fr\/from-the-suspiros-de-arena-series-12\/#mainImage","width":1348,"height":1340,"caption":"14.From the Suspiros de Arena series, 2025"},"primaryImageOfPage":{"@id":"https:\/\/artapartamento.com\/fr\/from-the-suspiros-de-arena-series-12\/#mainImage"},"datePublished":"2026-06-20T21:56:07+02:00","dateModified":"2026-06-20T21:57:59+02:00"},{"@type":"WebSite","@id":"https:\/\/artapartamento.com\/fr\/#website","url":"https:\/\/artapartamento.com\/fr\/","name":"El Apartamento","alternateName":"El Apartamento","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/artapartamento.com\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"El Apartamento |","og:type":"article","og:title":"From the Suspiros de Arena series | El Apartamento","og:description":"Arl\u00e9s del R\u00edo From the Suspiros de Arena series, 2025Sea sand on raw canvas100 x 100 cm (39.4 x 39.4 in) \u201cSuspiros de arena\u201d nace de un gesto que se define entre primario y meditativo: tomar arena entre las manos y soltarla con intenci\u00f3n sobre el lienzo crudo, como si cada forma fuera un aliento","og:url":"https:\/\/artapartamento.com\/fr\/from-the-suspiros-de-arena-series-12\/","og:image":"https:\/\/artapartamento.com\/wp-content\/uploads\/2026\/06\/14.From-the-Suspiros-de-Arena-series-2025.png.webp","og:image:secure_url":"https:\/\/artapartamento.com\/wp-content\/uploads\/2026\/06\/14.From-the-Suspiros-de-Arena-series-2025.png.webp","og:image:width":1348,"og:image:height":1340,"article:published_time":"2026-06-20T19:56:07+00:00","article:modified_time":"2026-06-20T19:57:59+00:00","article:publisher":"https:\/\/www.facebook.com\/p\/El-Apartamento-100069634825594\/","twitter:card":"summary_large_image","twitter:title":"From the Suspiros de Arena series | El Apartamento","twitter:description":"Arl\u00e9s del R\u00edo From the Suspiros de Arena series, 2025Sea sand on raw canvas100 x 100 cm (39.4 x 39.4 in) \u201cSuspiros de arena\u201d nace de un gesto que se define entre primario y meditativo: tomar arena entre las manos y soltarla con intenci\u00f3n sobre el lienzo crudo, como si cada forma fuera un aliento","twitter:image":"https:\/\/artapartamento.com\/wp-content\/uploads\/2023\/08\/El-Apartamento.png"},"aioseo_meta_data":{"post_id":"23261","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-06-20 19:56:09","updated":"2026-06-20 19:56:09","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/artapartamento.com\/fr\" title=\"Hogar\">Hogar<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tFrom the Suspiros de Arena series\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Hogar","link":"https:\/\/artapartamento.com\/fr"},{"label":"From the Suspiros de Arena series","link":"https:\/\/artapartamento.com\/fr\/from-the-suspiros-de-arena-series-12\/"}],"_links":{"self":[{"href":"https:\/\/artapartamento.com\/fr\/wp-json\/wp\/v2\/pages\/23261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artapartamento.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/artapartamento.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/artapartamento.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/artapartamento.com\/fr\/wp-json\/wp\/v2\/comments?post=23261"}],"version-history":[{"count":4,"href":"https:\/\/artapartamento.com\/fr\/wp-json\/wp\/v2\/pages\/23261\/revisions"}],"predecessor-version":[{"id":23268,"href":"https:\/\/artapartamento.com\/fr\/wp-json\/wp\/v2\/pages\/23261\/revisions\/23268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artapartamento.com\/fr\/wp-json\/wp\/v2\/media\/23257"}],"wp:attachment":[{"href":"https:\/\/artapartamento.com\/fr\/wp-json\/wp\/v2\/media?parent=23261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/artapartamento.com\/fr\/wp-json\/wp\/v2\/categories?post=23261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/artapartamento.com\/fr\/wp-json\/wp\/v2\/tags?post=23261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}